{"id":858,"date":"2019-01-16T17:03:56","date_gmt":"2019-01-16T16:03:56","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/news\/dal_consolato\/2019\/01\/programma-di-donazione-di-medicinali\/"},"modified":"2019-01-16T17:03:56","modified_gmt":"2019-01-16T16:03:56","slug":"programma-di-donazione-di-medicinali","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/it\/news\/dal_consolato\/2019\/01\/programma-di-donazione-di-medicinali\/","title":{"rendered":"Programma di donazione di medicinali per i cittadini italiani in Venezuela"},"content":{"rendered":"<p>A seguito di accordi raggiunti con le competenti Autorit\u00e0 venezuelane e al termine di un complesso<br \/>procedimento avviato di concerto e grazie al sostegno del Ministero degli Affari Esteri e della<br \/>Cooperazione Internazionale e in particolare della Direzione Generale per gli<br \/>Italiani all\u2019Estero e le Politiche Migratorie, l\u2019Ambasciata d\u2019Italia a Caracas \u00e8<br \/>riuscita ad avviare un programma di fornitura di medicine a favore dei<br \/>cittadini italiani residenti in Venezuela, che si trovano nella necessit\u00e0 di<br \/>disporre delle medesime e nell\u2019impossibilit\u00e0 di reperirle nel paese.<\/p>\n<p>Gli aspetti operativi del programma sono affidati al Consolato d\u2019Italia a Caracas,<br \/>che da questo punto di vista coprir\u00e0 l\u2019intero territorio nazionale, compresa la<br \/>circoscrizione del Consolato d\u2019Italia a Maracaibo, che tuttavia interverr\u00e0 per<br \/>gli aspetti di propria competenza. Si tratta del \u201cPrograma de donaci\u00f3n de<br \/>medicamentos para ciudadanos italianos en Venezuela\u201d, che provveder\u00e0 alla<br \/>consegna delle medicine agli interessati.<\/p>\n<p>Il sistema operativo \u00e8 molto semplice. Il programma dispone di 24 filiali in tutto<br \/>il paese. Chiunque abbia necessit\u00e0 di medicine dovr\u00e0 chiamare il numero<br \/>+582122104665 e seguire le indicazioni, avendo in particolare a portata di mano<br \/>l\u2019ultima ricetta medica, il nominativo del proprio medico e gli estremi del<br \/>proprio documento d\u2019identit\u00e0. L\u2019interessato dovr\u00e0 recarsi personalmente presso<br \/>il punto pi\u00fa vicino alla propria localit\u00e0 di residenza, indicatogli dal centralino stesso, ove il personale medico<br \/>autorizzato lo ricever\u00e0. Il programma di donazione provveder\u00e0 quindi alla<br \/>consegna delle medicine. L\u2019operazione \u00e8 completamente gratuita.<\/p>\n<p>\u00c8 opportuno sottolineare che il servizio \u00e8 autorizzato esclusivamente per i<br \/>cittadini italiani residenti in Venezuela e iscritti all\u2019AIRE di uno dei due<br \/>uffici consolari; che le medicine debbono essere di uso strettamente personale,<br \/>senza alcuna eccezione, e che la quantit\u00e0 da consegnare sar\u00e0 esclusivamente e<br \/>senza eccezione quella indicata dal personale medico autorizzato.<\/p>\n<p>Il metodo operativo \u00e9 esclusivamente quello sopra descritto e pertanto nessuna<br \/>istituzione dovr\u00e1 farsi tramite n\u00e9 segnalare all\u2019Ambasciata o agli Uffici<br \/>consolari nominativi di persone che abbiano bisogno di medicine: il sistema<br \/>operativo \u00e8 di facile accesso e, si ribadisce, gratuito e strettamente<br \/>personale.<\/p>\n","protected":false},"excerpt":{"rendered":"A seguito di accordi raggiunti con le competenti Autorit\u00e0 venezuelane e al termine di un complessoprocedimento avviato di concerto e grazie al sostegno del Ministero degli Affari Esteri e dellaCooperazione Internazionale e in particolare della Direzione Generale per gliItaliani all\u2019Estero e le Politiche Migratorie, l\u2019Ambasciata d\u2019Italia a Caracas \u00e8riuscita ad avviare un programma di fornitura [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-858","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=858"}],"version-history":[{"count":0,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/858\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=858"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}