{"id":798,"date":"2020-03-16T03:09:18","date_gmt":"2020-03-16T02:09:18","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/news\/dal_consolato\/2020\/03\/emergenza-covid-19-coronavirus_1\/"},"modified":"2020-03-16T03:09:18","modified_gmt":"2020-03-16T02:09:18","slug":"emergenza-covid-19-coronavirus_1","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/it\/news\/dal_consolato\/2020\/03\/emergenza-covid-19-coronavirus_1\/","title":{"rendered":"Emergenza COVID-19 (CORONAVIRUS) &#8211; INTRODUZIONE DELLO STATO DI EMERGENZA SANITARIA NAZIONALE IN VENEZUELA"},"content":{"rendered":"<p>Il 12 marzo il Presidente della Repubblica Maduro ha annunciato lo stato di emergenza del sistema sanitario nazionale e la sospensione dei voli da e per il Venezuela provenienti dall&#8217;Europa, dalla Colombia, da Panama e dalla Repubblica Dominicana, per un periodo di 30 giorni. Le frontiere con la Colombia e il Brasile sono state chiuse. Eventuali altre restrizioni in merito ai voli provenienti dall&#8217;Asia possono essere adottate nei prossimi giorni. <strong>A partire dal 16 marzo le Autorit\u00e0 venezuelane hanno disposto la quarantena obbligatoria (divieto di circolazione quasi assoluto e chiusura di quasi tutti gli uffici e gli esercizi commerciali) per la citt\u00e0 di Caracas ed per i seguenti Stati del Paese: Miranda, Vargas, Zulia, T\u00e1chira, Apure, Cojedes.<\/strong> <strong>A partire dal 17 marzo la quarantena obbligatoria \u00e8 stata estesa a tutto il Paese.<\/strong><\/p>\n<p>Considerata la progressiva cancellazione da parte delle compagnie aeree di voli, da ultimo i collegamenti aerei tra USA ed Europa, si consiglia quindi di attivarsi con LA MASSIMA URGENZA sia con la propria compagnia aerea che con le altre compagnie aeree per fare IMMEDIATO RIENTRO IN EUROPA, considerando anche opzioni di volo alternative a quelle inizialmente programmate.<\/p>\n<p>Si consiglia di consultare anche i siti delle Ambasciate italiane nei Paesi in cui e\u2019 previsto lo scalo per un aggiornamento sulle modalita\u2019 di rientro in Italia. Non si esclude inoltre la possibile prossima sospensione di altri collegamenti aerei. In tale quadro, in continua ed imprevedibile evoluzione, si suggerisce quindi di individuare IL PRIMA POSSIBILE un volo che consenta di fare rientro in Europa, che rende ad ogni modo piu\u2019 agevole il rientro in Italia, evitando di trovarsi bloccati oltre-oceano.<\/p>\n<p>I connazionali residenti\/domiciliati in Italia (come i cittadini stranieri), che si trovino all\u2019estero, possono infatti \u2013 ove i mezzi di trasporti siano operativi &#8211; fare ingresso in Italia per rientrare al proprio domicilio, abitazione o residenza.<\/p>\n<p>Facendo presente che sono assolutamente da evitare i viaggi per motivi di turismo in Italia e l\u2019ingresso e\u2019 consentito SOLO per comprovate esigenze lavorative, si informa che tutte le misure restrittive della libert\u00e0 di movimenti sull\u2019intero territorio italiano SI APPLICANO ANCHE AI CITTADINI STRANIERI.<\/p>\n<p>La Presidenza del Consiglio dei Ministri ha inoltre risposto alle domande frequenti, consultabili al seguente link: <a href=\"http:\/\/www.governo.it\/it\/articolo\/decreto-iorestoacasa-domande-frequenti-sulle-misure-adottate-dal-governo\/14278\">http:\/\/www.governo.it\/it\/articolo\/decreto-iorestoacasa-domande-frequenti-sulle-misure-adottate-dal-governo\/14278<\/p>\n<p><\/a><a href=\"http:\/\/www.governo.it\/it\/articolo\/decreto-iorestoacasa-domande-frequenti-sulle-misure-adottate-dal-governo\/14278\"><\/a><\/p>\n<p>Per aggiornamenti sulla situazione in Venezuela, \u00e8 possibile consultare i siti:<br \/>&#8211; Ministerio del Poder Popular para la Salud &#8211; <a href=\"http:\/\/www.mpps.gob.ve\">http:\/\/www.mpps.gob.ve<\/a><br \/>&#8211; Servicio Administrativo de Identificaci\u00f3n, Migraci\u00f3n y Extranjer\u00eda (SAIME) &#8211; <a href=\"http:\/\/www.saime.gob.ve\">http:\/\/www.saime.gob.ve<\/p>\n<p><\/a><a href=\"http:\/\/www.saime.gob.ve\"><\/a><\/p>\n<p>Per maggiori informazioni sulle misure adottate in Italia, \u00e8 possibile consultare i siti:<br \/>&#8211; Presidenza del Consiglio dei Ministri (<a href=\"http:\/\/www.governo.it\">http:\/\/www.governo.it<\/a>)<br \/>&#8211; Ministero della Salute (<a href=\"http:\/\/www.salute.gov.it\/portale\/home.html\">http:\/\/www.salute.gov.it\/portale\/home.html<\/a>)<br \/>&#8211; Ministero dell\u2019Interno (<a href=\"https:\/\/www.interno.gov.it\">https:\/\/www.interno.gov.it<\/a>)<br \/>&#8211; Ministero degli Affari Esteri e della Cooperazione Internazionale (<a href=\"https:\/\/www.esteri.it\">https:\/\/www.esteri.it<\/a>\u00a0 e\u00a0 <a href=\"http:\/\/www.viaggiaresicuri.it)\">http:\/\/www.viaggiaresicuri.it)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Il 12 marzo il Presidente della Repubblica Maduro ha annunciato lo stato di emergenza del sistema sanitario nazionale e la sospensione dei voli da e per il Venezuela provenienti dall&#8217;Europa, dalla Colombia, da Panama e dalla Repubblica Dominicana, per un periodo di 30 giorni. Le frontiere con la Colombia e il Brasile sono state chiuse. [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-798","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=798"}],"version-history":[{"count":0,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/798\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=798"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}