{"id":786,"date":"2020-04-14T21:31:00","date_gmt":"2020-04-14T19:31:00","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/news\/dal_consolato\/2020\/04\/corsi-online-di-preparazione-esame\/"},"modified":"2020-04-14T21:31:00","modified_gmt":"2020-04-14T19:31:00","slug":"corsi-online-di-preparazione-esame","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/it\/news\/dal_consolato\/2020\/04\/corsi-online-di-preparazione-esame\/","title":{"rendered":"Corsi online di preparazione esame PLIDA B1 cittadinanza"},"content":{"rendered":"<p>Le Scuole di Italiano della Societ\u00e0 Dante Alighieri organizzano il corso online di preparazione all\u2019esame PLIDA livello B1 cittadinanza.<\/p>\n<p>Il corso, che inizier\u00e0 il prossimo 24 aprile, \u00e8 rivolto a tutti quegli studenti che vogliano familiarizzare con la struttura dell\u2019esame e che vogliano ottenere le strategie utili al superamento dell\u2019esame.<\/p>\n<p>Per ulteriori informazioni, si possibile scrivere all&#8217;indirizzo <a href=\"mailto:scuoleditaliano@ladante.it\">scuoleditaliano@ladante.it<\/a>\u00a0o visitare il link\u00a0<a href=\"http:\/\/www.ladante.it\">http:\/\/www.ladante.it<\/a>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Le Scuole di Italiano della Societ\u00e0 Dante Alighieri organizzano il corso online di preparazione all\u2019esame PLIDA livello B1 cittadinanza. Il corso, che inizier\u00e0 il prossimo 24 aprile, \u00e8 rivolto a tutti quegli studenti che vogliano familiarizzare con la struttura dell\u2019esame e che vogliano ottenere le strategie utili al superamento dell\u2019esame. Per ulteriori informazioni, si possibile [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-786","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=786"}],"version-history":[{"count":0,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/786\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=786"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}