{"id":776,"date":"2020-06-02T09:50:47","date_gmt":"2020-06-02T07:50:47","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/news\/dal_consolato\/2020\/06\/italia-celebra-la-festa-della-repubblica\/"},"modified":"2020-06-02T09:50:47","modified_gmt":"2020-06-02T07:50:47","slug":"italia-celebra-la-festa-della-repubblica","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/it\/news\/dal_consolato\/2020\/06\/italia-celebra-la-festa-della-repubblica\/","title":{"rendered":"Italia celebra la Festa della Repubblica en Venezuela"},"content":{"rendered":"<p style=\"text-align: center;\">La delegaci\u00f3n diplom\u00e1tica del pa\u00eds europeo presente en Caracas<br \/>conmemora su fiesta nacional con un video institucional, el lanzamiento<br \/>de un bolet\u00edn informativo \u201c<em><strong>Italia con te<\/strong><\/em>\u201d, el desarrollo de la \u201c<em><strong>Gu\u00eda Italia 2020<\/strong><\/em>\u201d, el obsequio digital,<br \/>el libro \u201c<em><strong>Piazze (In)visibili<\/strong><\/em>\u201d y los avances del programa de repatriaci\u00f3n durante la pandemia.<\/p>\n<p>Caracas &#8211; Este 2 de junio se conmemorar\u00e1 la Festa della Repubblica, una oportunidad de encuentro y uni\u00f3n para sus connacionales, que en la distancia buscan reinventarse para mantener la tradici\u00f3n, en medio de una situaci\u00f3n sin precedentes, no vista desde La Gripe Espa\u00f1ola en 1918. En esta oportunidad el simbolismo patrio es un grito de fe y de coraje que busca, ante el dolor de las innumerables p\u00e9rdidas, dar esperanza y pasi\u00f3n a un pueblo que necesita y lograr\u00e1 levantarse, para construir su futuro.<\/p>\n<p>Hoy, el tradicional Frecce Tricolori ser\u00e1 m\u00e1s que simb\u00f3lico: el sobrevuelo del prestigioso equipo acrob\u00e1tico, le devuelve al cielo azzurri el verde de los campos y la esperanza de tiempos mejores, el blanco de las cumbres y el rojo ardor de los volcanes para irrumpir con fuerza y paso seguro despu\u00e9s de la crisis sanitaria.<\/p>\n<p>As\u00ed como los actos y el tono de la Fiesta de la Rep\u00fablica Italiana cambiaron este a\u00f1o por el Covid-19, la Embajada de Italia en Caracas tambi\u00e9n se ha adaptado a estos tiempos de confinamiento en los hogares y trabaja en cinco proyectos con los que se propone mantener un contacto cercano con los italianos en el pa\u00eds.<\/p>\n<p><strong>Un video para el reencuentro<\/strong><\/p>\n<p>\u201c<strong>En ocasi\u00f3n de la Fiesta Nacional, todas las Embajadas de Italia en el mundo y difundiendo el mensaje del Jefe de Estado Sergio Mattarella, han realizado videos conmemorativos para saludar a sus conciudadanos. En Venezuela, pensamos oportuno que el \u201cSistema Pa\u00eds\u201d pudiera ser representado en este mensaje y ser\u00e1 un placer si todos pueden colaborar para que llegue a la casa de cada italiano en Venezuela<\/strong>\u201d, manifest\u00f3 Placido Vigo, Embajador de Italia en Venezuela.<\/p>\n<p>El video conmemorativo del Aniversario de la Rep\u00fablica italiana, presenta un mensaje institucional positivo, de solidaridad, empat\u00eda, afecto y fortaleza, para que los italianos en Venezuela tengan presente \u201cque no est\u00e1n solos\u201d.<\/p>\n<p>El audiovisual est\u00e1 disponible en todas las redes de la Embajada, el Instituto Italiano de Cultura de Caracas, Consulados, Cavenit, Centros \u00cdtalos, entre otros.<\/p>\n<p><strong>Italia con te<\/strong><\/p>\n<p>Este 2 de junio llega a los correos electr\u00f3nicos de los integrantes de la gran familia \u00edtalo- venezolana el n\u00famero uno de \u201c<strong>Italia con te<\/strong>\u201d (Italia contigo), un newsletter para quienes hacen vida en la \u201cpeque\u00f1a Venecia\u201d. \u201c<strong>Hoy estamos publicando la primera edici\u00f3n del bolet\u00edn de los italianos en Venezuela, que estar\u00e1 siempre repleto de todas las contribuciones de los colaboradores y personajes activos de nuestra comunidad<\/strong>\u201d, explic\u00f3 el embajador Vigo.<\/p>\n<p>\u201c<strong>Italia con te<\/strong>\u201d nace con el objetivo de acercar a los italianos, a los diferentes temas y actividades comerciales, sociales, legales, culturales y consulares para as\u00ed, hacerlos parte de un todo, que es representado en el Sistema Pa\u00eds.<\/p>\n<p>El novedoso bolet\u00edn, ideado y desarrollado por la Embajada, en colaboraci\u00f3n con todas las instituciones que conforman las m\u00e1s importantes alianzas estrat\u00e9gicas, ofrecer\u00e1 a sus suscriptores, aliados y connacionales, noticias y art\u00edculos de opini\u00f3n que poseen informaci\u00f3n actual, vigente y de valor para sectores espec\u00edficos.<\/p>\n<p><strong>Gu\u00eda informativa<\/strong><\/p>\n<p>La Embajada trabaja este a\u00f1o en la elaboraci\u00f3n de la \u201c<strong>Gu\u00eda Italia 2020<\/strong>\u201d, una publicaci\u00f3n completa para el uso de los italianos en Venezuela, con todo lo relacionado sobre: informaci\u00f3n gubernamental, cultura, tr\u00e1mites administrativos y de negocios, que cualquier ciudadano o empresa italiana pueda necesitar o realizar en el pa\u00eds.<\/p>\n<p>El ambicioso proyecto editorial tiene como antecedentes otras gu\u00edas que se publicaron con \u00e9xito en Panam\u00e1, Argentina y Bolivia. El embajador Placido Vigo espera llevar a cabo esta iniciativa que promete m\u00e1s de 300 p\u00e1ginas a todo color, en las que se mostrar\u00e1n los aspectos de la vida en Venezuela, con especial acento en la italianidad y el legado de los emigrantes, que hicieron de este pa\u00eds su tierra y con empe\u00f1o labraron su futuro y el de sus hijos.<\/p>\n<p>Vigo tambi\u00e9n mencion\u00f3 que pr\u00f3ximamente se presentar\u00e1 el plan de innovaci\u00f3n tecnol\u00f3gica digital, que adelantan el Ministerio de Asuntos Exteriores y Cooperaci\u00f3n Internacional y su Embajada en Venezuela, para que sus ciudadanos puedan hacer tr\u00e1mites en el Consulado General de Italia en Caracas y en el Consulado de Maracaibo, de forma m\u00e1s inmediata desde su tel\u00e9fono inteligente.<\/p>\n<p><strong>Vuelos de regreso a casa<\/strong><\/p>\n<p>El embajador Vigo record\u00f3 que han trabajado activamente en la repatriaci\u00f3n de connacionales desde el bloqueo del espacio a\u00e9reo venezolano el pasado 16 de marzo, como parte de las medidas para mitigar el avance del coronavirus. \u201c<strong>Hemos organizado un total de 19 vuelos (de los cuales ocho fueron internos y cuatro de pa\u00edses de acreditaci\u00f3n secundarios), todo para repatriar a un total de 380 italianos (59 de ellos de las Antillas Orientales)<\/strong>\u201d, enumer\u00f3.<\/p>\n<p>En todo el mundo, Italia ha repatriado m\u00e1s de 88.000 ciudadanos en m\u00e1s de 920 operaciones. El esfuerzo de la delegaci\u00f3n diplom\u00e1tica presente en Caracas para llevar a casa a sus compatriotas, es un trabajo conjunto de la red de oficinas del Ministerio italiano de Relaciones Exteriores, en coordinaci\u00f3n con las dem\u00e1s administraciones locales para servir a sus ciudadanos cuando m\u00e1s lo necesitan.<\/p>\n<p><strong>Un obsequio digital<\/strong><\/p>\n<p>Para este nuevo aniversario del 2 de junio, el Ministerio de Asuntos Exteriores y Cooperaci\u00f3n Internacional, anunci\u00f3 tambi\u00e9n la distribuci\u00f3n de un obsequio digital, el libro \u201c<strong>Piazze (In)visibili<\/strong>\u201d, un texto editado por Marco Delogu y realizado con las fotograf\u00edas del autor de 20 plazas italianas, retratadas en el per\u00edodo comprendido entre finales de marzo y principios de mayo, en el que Italia, como buena parte del resto del mundo, pas\u00f3 por la dif\u00edcil fase de confinamiento, con calles y plazas solitarias, que adquirieron \u201cla funci\u00f3n sin precedentes de espacio f\u00edsico abierto, redescubriendo l\u00edneas arquitect\u00f3nicas previamente ocultas\u201d y ofreciendo \u201cnuevas perspectivas de luz\u201d.<\/p>\n<p>Acompa\u00f1adas por breves textos de escritores italianos, las fotograf\u00edas son \u201cpara todos aquellos en el extranjero que idealmente se unen este a\u00f1o para celebrar el D\u00eda de la Rep\u00fablica, esperando poder regresar para hacerlo f\u00edsicamente. Es una forma adicional de subrayar el papel que el mundo de la cultura y la creatividad italiana puede y debe desempe\u00f1ar para acompa\u00f1ar la reapertura y revitalizaci\u00f3n de nuestro sistema de pa\u00eds en el extranjero, que el Ministerio de Relaciones Exteriores seguir\u00e1 desempe\u00f1ando\u201d, manifest\u00f3 el ministro Luigi Di Maio en una misiva.<\/p>\n<p>El libro \u201c<strong>Piazze (In)visibili<\/strong>\u201d se distribuir\u00e1 por correo electr\u00f3nico a toda la base de datos de la delegaci\u00f3n diplom\u00e1tica y el Instituto Italiano de Cultura de Caracas, as\u00ed como a trav\u00e9s de sus redes sociales.<\/p>\n<p>Para conocer detalles de cada uno de los proyectos y las actividades, pueden visitar los portales web <a href=\"http:\/\/www.iiccaracas.esteri.it\">www.iiccaracas.esteri.it<\/a>\u00a0y <a href=\"http:\/\/www.ambcaracas.esteri.it\">www.ambcaracas.esteri.it<\/a>. Seguir las cuentas en redes sociales a trav\u00e9s de Facebook: Instituto Italiano de Cultura de Caracas, Twitter: @ItalyinVen @iicdecaracas e Instagram @iicdecaracas<\/p>\n<p>\u00a0<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/-a235A4d6dQ\" frameborder=\"0\" width=\"560\" height=\"315\" allowfullscreen=\"allowfullscreen\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" style=\"margin-right: auto; margin-left: auto; display: block;\"><\/iframe><\/p>\n<p style=\"text-align: center;\">\u00a0<\/p>\n<p style=\"text-align: center;\">El video conmemorativo del Aniversario de la Rep\u00fablica italiana, presenta un mensaje institucional positivo, de solidaridad, empat\u00eda, afecto y fortaleza, para que los italianos en Venezuela tengan presente \u201cque no est\u00e1n solos\u201d.<\/p>\n<p style=\"text-align: center;\">\u00a0<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/FrTuTnvRtto\" frameborder=\"0\" width=\"560\" height=\"315\" allowfullscreen=\"allowfullscreen\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" style=\"margin-right: auto; margin-left: auto; display: block;\"><\/iframe><\/p>\n<p style=\"text-align: center;\">\u00a0<\/p>\n<p style=\"text-align: center;\">&#8220;Inno Italia&#8221; interpretado por la Orquesta<br \/>y el Coro de la Accademia Chigiana<\/p>\n<p>El video contiene la interpretaci\u00f3n del Himno Nacional de Italia a cargo de la Orquesta y el Coro de la Accademia Chigiana, una hist\u00f3rica instituci\u00f3n musical italiana de alta formaci\u00f3n, con sede en Siena. La presentaci\u00f3n involucr\u00f3 a 108 m\u00fasicos, inclu\u00eddos estudiantes, maestros y colaboradores de la Academia, as\u00ed como importantes artistas de la m\u00fasica cl\u00e1sica internacional como Salvatore Accardo, Bruno Giuranna, Antonio Meneses, David Geringas, Alessandro Carbonare, Pino Ettorre, Luca Sanzo, Francesco Dillon, Matteo Cesari, Paolo Ravaglia, Giulio Rovighi y el Quartetto Nous.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ambcaracas.esteri.it\/Ambasciata_Caracas\/resource\/img\/2020\/06\/piazze_invisibili.jpg\" alt=\"\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.venezuelasinfonica.com\/Italia\/piazze_in_visibili_baja.pdf\" target=\"_parent\" rel=\"noopener\">Le &#8220;Piazze (In)visibili&#8221; Download PDF<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/bit.ly\/3cmyvK2\">Le &#8220;Piazze (In)visibili&#8221; Download ePub<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: center;\"><strong>Le \u201cPiazze (In)visibili\u201d come dono digitale<\/strong><\/p>\n<p>Nella ricorrenza del 2 giugno, ci \u00e8 sembrato giusto fare dono di questa opera a tutti coloro che, all\u2019estero, si uniscono quest\u2019anno idealmente per celebrare la Festa della Repubblica, in attesa di poter tornare a farlo fisicamente. E\u2019 un ulteriore modo per sottolineare il ruolo che il mondo della cultura e della creativit\u00e0 italiane pu\u00f2 e deve svolgere per accompagnare la riapertura e il rilancio del nostro Sistema Paese all\u2019estero, che il Ministero degli Esteri continuer\u00e0 a sostenere. Siamo coscienti di essere di fronte a grandi sfide, ma consapevoli al tempo stesso di avere la capacit\u00e0 di affrontarle. E dallo sguardo rivolto verso il futuro traiamo la spinta per vincerle.<\/p>\n<p>In questi ultimi mesi, in cui le citt\u00e0 si sono fermate per contenere l\u2019epidemia che ha investito il mondo, in cui gli incontri tra le persone sono diventati \u201cassembramenti\u201d da evitare &#8211; una situazione alla quale, voglio sottolinearlo, il popolo italiano ha risposto con encomiabile senso di responsabilit\u00e0 &#8211; la piazza ha perso momentaneamente la sua funzione sociale ed ha acquistato quella, inedita, di spazio fisico aperto, riscoprendo linee architettoniche prima nascoste e prospettive di luce nuove. Come in un quadro di De Chirico, l\u2019architettura \u00e8 emersa in primo piano e le piazze si sono rivelate nelle loro linee essenziali, come i loro artefici le avevano immaginate. Di ci\u00f2 danno testimonianza le immagini di questo volume, curato da Marco Delogu e realizzato con le fotografie d\u2019autore di 20 piazze italiane, ritratte nel periodo tra la fine di marzo e l\u2019inizio di maggio, in cui l\u2019Italia, come buona parte del resto del mondo, ha vissuto la difficile fase del confinamento. Alle fotografie sono stati affiancati brevi testi originali di scrittori italiani, legati a quei luoghi e a quelle piazze da ricordi, esperienze e suggestioni letterarie.<\/p>\n<p>Quando si parla di Italia all\u2019estero, non si pu\u00f2 non pensare al nostro patrimonio storico e culturale che ogni anno porta milioni di turisti a visitare il nostro Paese. Quando si pensa alle citt\u00e0 e ai mille borghi d\u2019Italia, che attirano i viaggiatori da tutto il mondo, l\u2019immagine che immediatamente ci viene alla mente \u00e8 quella della piazza, che \u00e8 insieme la cornice e la tela su cui si disegnano palazzi, chiese, monumenti e la vita che si svolge intorno ad essi. La piazza diventa sinonimo di patrimonio culturale, ma anche di luogo dell\u2019incontro e della socialit\u00e0, dello scambio commerciale e della dialettica delle idee. Come scrisse Italo Calvino ne \u201cLe citt\u00e0 invisibili\u201d- titolo a cui ci siamo ispirati- \u201cogni volta che si entra nella piazza ci si trova in mezzo ad un dialogo\u201d.<\/p>\n<p style=\"text-align: right;\"><strong>Luigi Di Maio<\/strong><br \/>Ministro degli Affari Esteri e della Cooperazione Internazionale<\/p>\n<p>* * * *<\/p>\n<p style=\"text-align: center;\"><strong>Las \u201cPlazas (In)visibles\u201d como obsequio digital<\/strong><\/p>\n<p>Al hablar de Italia en el exterior, no se puede dejar de pensar en nuestro patrimonio hist\u00f3rico y cultural que cada a\u00f1o lleva a millones de turistas a visitar nuestro pa\u00eds. Al pensar en las ciudades y en los miles de ciudades de Italia que atraen a viajeros de todo el mundo, la imagen que enseguida viene a la mente, es la de una plaza, que es a la vez el marco y el lienzo en el que se dibujan palacios, iglesias, monumentos, y la vida que se desarrolla alrededor de los mismos. La plaza se convierte en sin\u00f3nimo de patrimonio cultural, pero tambi\u00e9n en el lugar para el encuentro y la sociabilidad, para el intercambio comercial y para la dial\u00e9ctica de las ideas. Como escribi\u00f3 Italo Calvino en \u201cLas ciudades invisibles\u201d- t\u00edtulo en el que nos inspiramos \u2013 \u201ccada vez que uno entra en la plaza se encuentra en medio de un di\u00e1logo\u201d<\/p>\n<p>En estos \u00faltimos meses en los que las ciudades se han detenido para contener la epidemia que ha golpeado al mundo entero y durante los cuales los encuentros personales se han vuelto \u201caglomeraciones\u201d que hay que evitar \u2013 situaci\u00f3n ante la cual, quiero destacar, el pueblo italiano ha sabido responder con encomiable responsabilidad \u2013 las plazas han perdido temporalmente su funci\u00f3n social para adquirir otra, in\u00e9dita, la de un espacio f\u00edsico abierto, dejando al descubierto l\u00edneas arquitect\u00f3nicas antes escondidas y nuevas perspectivas de luz. Como en un cuadro de &#8220;De Chirico&#8221;, la arquitectura se ha puesto de manifiesto en primer plano, y las plazas se han mostrado en sus l\u00edneas esenciales, como las hab\u00edan imaginado sus creadores. De esto dan testimonio las im\u00e1genes del presente volumen, que cont\u00f3 con la curadur\u00eda de Marco Delogu, y fue realizado con fotograf\u00edas de autor captadas entre finales de marzo e inicios de mayo, de 20 plazas italianas, cuando Italia, al igual que gran parte del mundo, padeci\u00f3 la fase dif\u00edcil del confinamiento. Acompa\u00f1an a las fotograf\u00edas breves textos originales de escritores italianos vinculados con esos lugares y con esas plazas por recuerdos, experiencias y sugestiones literarias.<\/p>\n<p>Con motivo del aniversario de la Rep\u00fablica de Italia del 2 de junio, nos ha parecido correcto regalarle esta obra a todos los que se unen este a\u00f1o idealmente en el exterior para celebrar la Fiesta de la Rep\u00fablica, mientras esperan poder hacerlo f\u00edsicamente. Es una manera adicional para destacar el rol que el mundo de la cultura y de la creatividad de Italia puede y debe llevar a cabo para acompa\u00f1ar la reapertura y el relanzamiento de nuestro Sistema Pa\u00eds en el exterior, que seguir\u00e1 contando con el respaldo del Ministerio de Relaciones Exteriores. Somos conscientes de estar frente a grandes retos, pero tambi\u00e9n tenemos la certeza que poseemos las capacidades requeridas para afrontarlos. Y con la mirada puesta en el futuro sacamos el empuje para superarlos<\/p>\n<p style=\"text-align: right;\"><strong>Luigi Di Maio<\/strong><br \/>Ministro de Relaciones Exteriores y de Cooperaci\u00f3n Internacional<\/p>\n","protected":false},"excerpt":{"rendered":"La delegaci\u00f3n diplom\u00e1tica del pa\u00eds europeo presente en Caracasconmemora su fiesta nacional con un video institucional, el lanzamientode un bolet\u00edn informativo \u201cItalia con te\u201d, el desarrollo de la \u201cGu\u00eda Italia 2020\u201d, el obsequio digital,el libro \u201cPiazze (In)visibili\u201d y los avances del programa de repatriaci\u00f3n durante la pandemia. Caracas &#8211; Este 2 de junio se conmemorar\u00e1 [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-776","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=776"}],"version-history":[{"count":0,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/776\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=776"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}