{"id":726,"date":"2021-08-26T18:59:51","date_gmt":"2021-08-26T16:59:51","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/news\/dal_consolato\/2021\/08\/novita-elezioni-comites-presentazione\/"},"modified":"2021-08-26T18:59:51","modified_gmt":"2021-08-26T16:59:51","slug":"novita-elezioni-comites-presentazione","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/it\/news\/dal_consolato\/2021\/08\/novita-elezioni-comites-presentazione\/","title":{"rendered":"NOVITA&#8217; ELEZIONI COMITES PRESENTAZIONE DELLE LISTE DEI CANDIDATI E AUTENTICAZIONE DELLE FIRME DEI SOTTOSCRITTORI"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>ELEZIONI COMITES PRESENTAZIONE DELLE LISTE DEI CANDIDATI E AUTENTICAZIONE DELLE FIRME DEI SOTTOSCRITTORI.<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>ATTENZIONE: Ai sensi delle disposizioni vigenti,\u00a0i Comitati di Caracas e di Puerto Ordaz saranno composti da 12 membri, considerato il numero dei cittadini italiani residenti nella circoscrizione consolare<\/strong><\/span><strong>. <\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>A) CANDIDATI: REQUISITI, INELEGGIBILITA\u2019 E INCANDIDABILITA\u2019<\/strong><\/p>\n<p>A.1) ELEGGIBILITA\u2019 DEI CANDIDATI<br \/>Ai sensi dell\u2019art. 5 della Legge 286\/2003, sono eleggibili i cittadini italiani residenti nella circoscrizione consolare e candidati in una delle liste presentate, purch\u00e9 iscritti nell\u2019elenco aggiornato di cui all\u2019art. 5 comma 1 della Legge 459\/2001 e in possesso dei requisiti per essere candidati alle consultazioni elettorali amministrative.<br \/>La candidatura \u00e8 ammessa solo in una circoscrizione e per una sola lista.<br \/>Ai sensi dell\u2019art. 6 del DPR 395\/2003, i candidati devono essere in possesso dei requisiti previsti per godere di elettorato passivo (art. 55, comma 1, del D.Lgs. 267\/2000).<\/p>\n<p>A.2) INELEGGIBILITA\u2019 E INCANDIDABILITA\u2019<br \/>Ai sensi dell\u2019art. 5, comma 4, della Legge, non sono eleggibili i dipendenti dello Stato italiano che prestano servizio all\u2019estero, ivi compresi il personale a contratto, nonch\u00e9 coloro che detengono cariche istituzionali e i loro collaboratori salariati. Non sono altres\u00ec eleggibili gli amministratori e i legali rappresentanti di enti gestori di attivit\u00e0 scolastiche che operano nel territorio del Comitato e gli amministratori e i legali rappresentanti dei comitati per l\u2019assistenza che ricevono finanziamenti pubblici.<br \/>Inoltre, l\u2019art. 6 del DPR 395\/2003, gi\u00e0 richiamato, rinvia alle condizioni di ineleggibilit\u00e0 e incandidabilit\u00e0 previste dagli articoli 60 (Ineleggibilit\u00e0) e 61 (Ineleggibilit\u00e0 e incompatibilit\u00e0 alla carica di sindaco e presidente di provincia) del D.Lgs. 267\/2000 e successive modifiche, nonch\u00e9 dagli articoli 10 (incandidabilit\u00e0 alle elezioni provinciali, comunali e circoscrizionali) e 11 (Sospensione e decadenza di diritto degli amministratori locali in condizione di incandidabilit\u00e0) del D.Lgs. 235\/2012.<br \/>Nel caso di candidatura in pi\u00f9 circoscrizioni o in pi\u00f9 liste, il candidato non \u00e8 eleggibile. Non sono infine eleggibili coloro che sono stati componenti di un Comitato per due mandati consecutivi (art. 8 della Legge).<\/p>\n<p><strong>B) PRESENTAZIONE DELLE LISTE DI CANDIDATI<\/strong><\/p>\n<p>Modello per la presentazione della lista di candidati <a href=\"resource\/doc\/2021\/09\/modello_di_dich_di_presentazione_lista_cand._atto_principale_-_modificato_-_dl.117-21-3.doc\" target=\"_parent\" rel=\"noopener\">ATTO PRINCIPALE<\/a><\/p>\n<p>Modello per la presentazione della lista dei sottoscrittori <a href=\"resource\/doc\/2021\/09\/modello_di_dich_di_presentazione_lista_cand._atto_separato_-_modificato_-_dl.117-21-2.doc\" target=\"_parent\" rel=\"noopener\">ATTO SEPARATO<\/a><\/p>\n<p>Modello per la designazione dei <a href=\"resource\/doc\/2021\/09\/designazione_rappresentati_di_lista_effettivo_e_supplente.docx\" target=\"_parent\" rel=\"noopener\">RAPPRESENTANTI DELLE LISTE<\/a><\/p>\n<p>Modello per la <a href=\"resource\/doc\/2021\/09\/modulo_accettazione_candidatura.docx\" target=\"_parent\" rel=\"noopener\">ACCETTAZIONE DELLA CANDIDATURA<\/a><\/p>\n<p><strong>Le liste sono formate da un numero di candidati almeno pari al numero dei membri del Comitato da eleggere e non superiore a 16 per i Comites composti da 12 membri<\/strong> o 22 per i Comites composti da 18 membri.<br \/><strong>Esse sono presentate nelle ore d\u2019ufficio all\u2019Ufficio elettorale dal ventesimo al trentesimo giorno successivo all\u2019indizione (ossia da gioved\u00ec 23 settembre a domenica 3 ottobre 2021).<\/strong><br \/>Le liste, ciascuna munita del proprio contrassegno, sono presentate da uno dei candidati o da un sottoscrittore. Il presentatore della lista dichiara il proprio domicilio ai fini delle successive notificazioni.<br \/>Ogni lista di candidati (ognuno con cognome, nome, luogo e data di nascita, nonch\u00e9 numero progressivo attribuito dal presentatore di lista) deve essere corredata della prescritta documentazione, ovvero:<br \/>a) le dichiarazioni, firmate e autenticate, di accettazione della candidatura di ciascun candidato corredate dai relativi certificati nei quali si attesta che i candidati sono iscritti negli elenchi elettorali della circoscrizione consolare, allo scopo di evitare che persone prive dell\u2019elettorato attivo partecipino alle elezioni in qualit\u00e0 di candidati (in conformit\u00e0 con le norme vigenti in materia elettorale);<br \/>b) la designazione di un rappresentante effettivo e di uno supplente per il comitato elettorale circoscrizionale;<br \/>c) le sottoscrizioni prescritte dalla legge. Per ogni sottoscrittore la lista deve recare il cognome, il nome, il luogo e la data di nascita e la certificazione elettorale.<br \/>N.B.: a seguito dell\u2019emanazione del DL 117\/2021, e limitatamente alle elezioni dei Com.It.Es. previste per il 2021, la firma dei sottoscrittori \u00e8 esente da autentica se accompagnata da un valido documento di identit\u00e0 o di riconoscimento o di documento equipollente ai sensi dell\u2019articolo 35 del decreto del Presidente della Repubblica 28 dicembre 2000, n. 445, anche rilasciato dalle competenti autorit\u00e0 del Paese di residenza.<br \/>I sottoscrittori delle liste devono essere residenti nella circoscrizione consolare (da almeno sei mesi in base all\u2019art.13, comma 1, Legge 286\/2003) e risultare negli elenchi elettori per le elezioni dei Comites.<br \/>I certificati, anche collettivi, che attestano l\u2019iscrizione dei sottoscrittori negli elenchi elettori per le elezioni dei Comites della relativa circoscrizione sono rilasciati dall\u2019ufficio consolare, a partire dal quindicesimo giorno successivo alla data di indizione delle elezioni (ossia dal 18 settembre 2021). Essi sono rilasciati su richiesta degli interessati e sulla base degli atti in possesso dell\u2019ufficio consolare e nel termine improrogabile di 24 ore dalla richiesta.<br \/>Le dichiarazioni di presentazione delle liste dei candidati possono essere firmate in atti (fogli) separati. Gli atti separati di raccolta delle firme riportano il contrassegno di lista, nonch\u00e9 tutti i nominativi dei candidati.<br \/>Si specifica che le firme dei presentatori di lista sono comunque autenticate dal funzionario consolare in considerazione del fatto che la legge prevede che il presentatore della lista si rechi all\u2019Ufficio consolare per consegnare la propria dichiarazione. Parimenti si rammenta che le sottoscrizioni alle accettazioni delle candidature sono egualmente soggette ad autentica.<\/p>\n<p><strong>SOTTOSCRIZIONI DELLE LISTE DEI CANDIDATI ED ESENZIONE AUTENTICA DELLE FIRME<\/strong><\/p>\n<p>Gli elettori sottoscrittori delle liste devono risultare iscritti nell\u2019elenco degli elettori residenti, non possono essere candidati e non possono sottoscrivere pi\u00f9 di una lista pena la nullit\u00e0 della sottoscrizione.<br \/>N.B.: a seguito dell\u2019emanazione del DL 117\/2021, e limitatamente alle elezioni dei Com.It.Es. previste per il 2021, il numero minimo di sottoscrizioni richieste per la presentazione delle liste di cui all\u2019articolo 15, comma 3, della legge 23 ottobre 2003, n. 286, \u00e8 fissato in CINQUANTA (anzich\u00e9 cento) per le collettivit\u00e0 composte da un numero di cittadini italiani fino a cinquantamila e in CENTO (anzich\u00e9 duecento) per quelle composte da un numero di cittadini italiani superiore a cinquantamila. Si rammenta che ai sensi dell\u2019art. 1 della L. 286\/2003, la consistenza numerica della collettivit\u00e0 residente si ricava dall\u2019elenco aggiornato al 31\/12\/2020 dei residenti all\u2019estero ex art. 5 della Legge 459\/2001.<br \/>Si ribadisce che le firme dei sottoscrittori non sono soggette ad autentica (vedasi punto B), fermo restando che le firme gi\u00e0 autenticate dagli Uffici consolari sono considerate valide a tutti gli effetti.<\/p>\n","protected":false},"excerpt":{"rendered":"ELEZIONI COMITES PRESENTAZIONE DELLE LISTE DEI CANDIDATI E AUTENTICAZIONE DELLE FIRME DEI SOTTOSCRITTORI. \u00a0 ATTENZIONE: Ai sensi delle disposizioni vigenti,\u00a0i Comitati di Caracas e di Puerto Ordaz saranno composti da 12 membri, considerato il numero dei cittadini italiani residenti nella circoscrizione consolare. \u00a0 A) CANDIDATI: REQUISITI, INELEGGIBILITA\u2019 E INCANDIDABILITA\u2019 A.1) ELEGGIBILITA\u2019 DEI CANDIDATIAi sensi dell\u2019art. [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-726","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=726"}],"version-history":[{"count":0,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/726\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=726"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}