{"id":1950,"date":"2024-05-21T09:46:31","date_gmt":"2024-05-21T13:46:31","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/?p=1950"},"modified":"2024-05-21T09:53:51","modified_gmt":"2024-05-21T13:53:51","slug":"elezioni-europee-2024","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/it\/news\/dal_consolato\/2024\/05\/elezioni-europee-2024\/","title":{"rendered":"Elezioni Europee 2024"},"content":{"rendered":"<p>La normativa relativa all\u2019elezione dei membri del Parlamento europeo spettanti all\u2019Italia non prevede il voto all\u2019estero al di fuori dei Paesi UE. Pertanto, gli elettori italiani, iscritti all\u2019AIRE e residenti negli Stati che non sono membri dell\u2019Unione Europea, potranno votare solo rientrando in Italia, recandosi presso i seggi istituiti dai Comuni nelle cui liste elettorali risultano iscritti.<br \/>\nA tal fine, i Comuni di iscrizione elettorale provvederanno ad inviare agli elettori una cartolina avviso recante l\u2019indicazione della data della votazione con l\u2019avvertenza che il destinatario potr\u00e0 ritirare il certificato elettorale presso il competente Ufficio comunale e che l\u2019esibizione della cartolina stessa d\u00e0 diritto al titolare di usufruire delle facilitazioni di viaggio in territorio nazionale per recarsi a votare nel comune di iscrizione.<\/p>\n","protected":false},"excerpt":{"rendered":"La normativa relativa all\u2019elezione dei membri del Parlamento europeo spettanti all\u2019Italia non prevede il voto all\u2019estero al di fuori dei Paesi UE. Pertanto, gli elettori italiani, iscritti all\u2019AIRE e residenti negli Stati che non sono membri dell\u2019Unione Europea, potranno votare solo rientrando in Italia, recandosi presso i seggi istituiti dai Comuni nelle cui liste elettorali [&hellip;]","protected":false},"author":3,"featured_media":1952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[8],"class_list":["post-1950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-elezioni"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=1950"}],"version-history":[{"count":4,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1950\/revisions"}],"predecessor-version":[{"id":1964,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1950\/revisions\/1964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/media\/1952"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=1950"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=1950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}