{"id":905,"date":"2017-10-06T17:05:45","date_gmt":"2017-10-06T15:05:45","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/news\/dal_consolato\/2017\/10\/traduzioni-2\/"},"modified":"2017-10-06T17:05:45","modified_gmt":"2017-10-06T15:05:45","slug":"traduzioni-2","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/es\/news\/dal_consolato\/2017\/10\/traduzioni-2\/","title":{"rendered":"Traducciones"},"content":{"rendered":"<p style=\"text-align: justify;\">En\u00a0conformidad a\u00a0las praxis seguidas por la Rep\u00fablica Bolivariana de Venezuela, este Consulado General proceder\u00e1 solamente a legalizar las firmas de los traductores oficiales cuyas firmas se encuentren depositadas ante el Ministerio de Interior y Justicia venezolano, por lo tanto no ser\u00e1 necesaria la doble Apostilla.<\/p>\n<p style=\"text-align: justify;\">Para las traducciones no efectuadas por un traductor oficial, este Consulado General tendr\u00e1 que certificar la conformidad al acta original en un per\u00edodo de 30 d\u00edas (Decreto del Ministro de Asuntos Exteriores 3 de marzo 1995, n. 171). En el caso en que la traducci\u00f3n no fuera confome al documento original, no se podr\u00e1 certificar y las actas ser\u00e1n restituidas al interesado, que tendr\u00e1 que solicitar otra cita, por consiguiente se aconseja encarecidamente a los usuarios que presten atenci\u00f3n a la calidad de la traducci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"En\u00a0conformidad a\u00a0las praxis seguidas por la Rep\u00fablica Bolivariana de Venezuela, este Consulado General proceder\u00e1 solamente a legalizar las firmas de los traductores oficiales cuyas firmas se encuentren depositadas ante el Ministerio de Interior y Justicia venezolano, por lo tanto no ser\u00e1 necesaria la doble Apostilla. Para las traducciones no efectuadas por un traductor oficial, este [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-905","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/comments?post=905"}],"version-history":[{"count":0,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/905\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/media?parent=905"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/tags?post=905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}