{"id":895,"date":"2018-03-04T14:43:39","date_gmt":"2018-03-04T13:43:39","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/news\/dal_consolato\/2018\/03\/accesso-ai-servizi-consolari-2\/"},"modified":"2018-03-04T14:43:39","modified_gmt":"2018-03-04T13:43:39","slug":"accesso-ai-servizi-consolari-2","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/es\/news\/dal_consolato\/2018\/03\/accesso-ai-servizi-consolari-2\/","title":{"rendered":"Acceso a los servicios consulares"},"content":{"rendered":"<p>Se comunica que para los siguientes casos no ser\u00e1 necesaria la cita online:<\/p>\n<p>1- Solicitud de servicios consulares por parte de un ciudadano <span style=\"text-decoration: underline;\"><strong>s\u00f3lo<\/strong><\/span> italiano (SIN doble ciudadan\u00eda);<\/p>\n<p>2- Solicitud de transmisi\u00f3n\u00a0del acta de nacimiento de un ni\u00f1o que no haya cumplido el a\u00f1o de edad;<\/p>\n<p>3- Solicitud de servicios consulares por parte de un ciudadano que haya cumplido 70 a\u00f1os de edad.<\/p>\n","protected":false},"excerpt":{"rendered":"Se comunica que para los siguientes casos no ser\u00e1 necesaria la cita online: 1- Solicitud de servicios consulares por parte de un ciudadano s\u00f3lo italiano (SIN doble ciudadan\u00eda); 2- Solicitud de transmisi\u00f3n\u00a0del acta de nacimiento de un ni\u00f1o que no haya cumplido el a\u00f1o de edad; 3- Solicitud de servicios consulares por parte de un [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-895","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/comments?post=895"}],"version-history":[{"count":0,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/895\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/media?parent=895"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/tags?post=895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}