{"id":847,"date":"2019-05-07T20:50:51","date_gmt":"2019-05-07T18:50:51","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/news\/dal_consolato\/2019\/05\/concorso-pubblico-della-carriera-2\/"},"modified":"2019-05-07T20:50:51","modified_gmt":"2019-05-07T18:50:51","slug":"concorso-pubblico-della-carriera-2","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/es\/news\/dal_consolato\/2019\/05\/concorso-pubblico-della-carriera-2\/","title":{"rendered":"CONCORSO PUBBLICO DELLA CARRIERA DEI FUNZIONARI TECNICI DELLA POLIZIA DI STATO"},"content":{"rendered":"<p>Sulla gazzetta ufficiale della Repubblica Italiana &#8211; 4 Serie Speciali \u00abConcorsi ed esami\u00bb del 3 maggio 2019 \u00e9 stato pubblicato un bando di concorso per Titoli ed Esami per il Conferimento di 19 posti di Commissario tecnico psicologo del ruolo degli psicologi, settore arruolamento e psicologia, dei funzionari tecnici della Polizia di Stato, indetto con decreto del Capo della Polizia &#8211; Direttore Generale della Pubblica Sicurezza del 2 maggio 2019. Il testo\u00a0\u00e9 consultabile sul sito internet della Polizia di Stato (<a href=\"http:\/\/www.poliziadistato.it\" title=\"Sito della Polizia di Stato\">www.poliziadistato.it<\/a>).<\/p>\n<p>Gli eventuali candidati che si trovano all&#8217;estero dovranno compilare le relative domande di ammissione al concorso e trasmetterle entro il termine di 30 giorni- e che decorre dal giorno successivo alla data della pubblicazione del presente bando sulla Gazzetta Ufficiale della Repubblica Italiana &#8211; utilizzando esclusivamente la procedura informatica disponibile all&#8217;indirizzo: <a href=\"http.\/%20concosionline.poliziadistato.it\" title=\"Sito concorso polizia di stato\">http.\/\/ concorsionline.poliziadistato.it<\/a> (dove si dovr\u00e1 cliccare sull&#8217;icone \u00abConcorso Pubblico\u00bb)<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Sulla gazzetta ufficiale della Repubblica Italiana &#8211; 4 Serie Speciali \u00abConcorsi ed esami\u00bb del 3 maggio 2019 \u00e9 stato pubblicato un bando di concorso per Titoli ed Esami per il Conferimento di 19 posti di Commissario tecnico psicologo del ruolo degli psicologi, settore arruolamento e psicologia, dei funzionari tecnici della Polizia di Stato, indetto con [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-847","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/comments?post=847"}],"version-history":[{"count":0,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/847\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/media?parent=847"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/tags?post=847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}