{"id":821,"date":"2020-01-08T15:13:16","date_gmt":"2020-01-08T14:13:16","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/news\/dal_consolato\/2020\/01\/rinvio-delle-elezioni-comites-dal-2\/"},"modified":"2020-01-08T15:13:16","modified_gmt":"2020-01-08T14:13:16","slug":"rinvio-delle-elezioni-comites-dal-2","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/es\/news\/dal_consolato\/2020\/01\/rinvio-delle-elezioni-comites-dal-2\/","title":{"rendered":"Rinvio delle Elezioni COMITES dal 2020 al 2021"},"content":{"rendered":"<p>S&#8217;informano i cittadini che, a seguito dell&#8217;approvazione del Decreto Legge n. 162\/2019, le elezioni per il rinnovo dei Comitati degli Italiani all&#8217;Estero (COMITES) e le elezioni per il rinnovo del Consiglio Generale degli Italiani all&#8217;Estero (CGIE), inizialmente previste per l&#8217;anno 2020, sono state rinviate al 2021.<\/p>\n<p>Le predette elezioni avranno comunque luogo tra il 15 aprile ed il 31 dicembre 2021.<\/p>\n","protected":false},"excerpt":{"rendered":"S&#8217;informano i cittadini che, a seguito dell&#8217;approvazione del Decreto Legge n. 162\/2019, le elezioni per il rinnovo dei Comitati degli Italiani all&#8217;Estero (COMITES) e le elezioni per il rinnovo del Consiglio Generale degli Italiani all&#8217;Estero (CGIE), inizialmente previste per l&#8217;anno 2020, sono state rinviate al 2021. Le predette elezioni avranno comunque luogo tra il 15 [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-821","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/comments?post=821"}],"version-history":[{"count":0,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/821\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/media?parent=821"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/tags?post=821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}