{"id":811,"date":"2020-02-28T13:41:03","date_gmt":"2020-02-28T12:41:03","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/news\/dal_consolato\/2020\/02\/emergenza-covid-19-situazione-reale-2\/"},"modified":"2020-02-28T13:41:03","modified_gmt":"2020-02-28T12:41:03","slug":"emergenza-covid-19-situazione-reale-2","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/es\/news\/dal_consolato\/2020\/02\/emergenza-covid-19-situazione-reale-2\/","title":{"rendered":"EMERGENCIA COVID-19 \u2013 SITUACI\u00d3N REAL EN ITALIA"},"content":{"rendered":"<p>1. La respuesta que Italia est\u00e1 dando a la emergencia COVID-19 (\u201cCoronavirus\u201d) ha sido tempestiva &#8211; como fue reconocido por la OMS y la UE &#8211; y marcada por la m\u00e1xima transparencia y claridad hacia la comunidad nacional y hacia los interlocutores internacionales. La preocupante proliferaci\u00f3n de noticias inexactas y alarmantes sobre la situaci\u00f3n sanitaria en Italia no refleja la realidad de un fen\u00f3meno de contagio que queda limitado a unas peque\u00f1as \u00e1reas restringidas en pocas Regiones.<\/p>\n<p>2. Los datos reales y la verdad son m\u00e1s importantes que cualquier otra reconstrucci\u00f3n aproximativa. A la fecha del 27 de febrero de 2020, los datos comprobados en Italia ascienden a 528, de los cuales 14 fallecidos y 37 curados. Con respecto al solo d\u00eda de ayer, se registr\u00f3 un incremento del 97% de los que sanaron, comparado con un aumento del 29% de las personas contagiadas, las cuales representan sin embargo una exigua minor\u00eda (4,8%) de las que fueron sometidos a examen, que ascienden a m\u00e1s de 11.000.<\/p>\n<p>3. Las \u00e1reas italianas en las cuales fueron tomadas medidas restrictivas se mantienen iguales: una en la regi\u00f3n Lombard\u00eda y otra en Veneto, y afectan apenas el 0.05% de todo el territorio nacional. Sobre la base de los controles constantemente realizados por las Autoridades competentes, no se hicieron necesarias medidas de limitaci\u00f3n de la circulaci\u00f3n en otras \u00e1reas.<\/p>\n<p>4. Todos los pacientes hospitalizados en el Instituto Nacional para las Enfermedades Infecciosas \u201cLazzaro Spallanzani\u201d en Roma, incluyendo a los turistas chinos que hab\u00edan resultado por primeros ser positivos al test del Coronavirus, est\u00e1n curados. Italia es un Pa\u00eds transparente, fiable y est\u00e1 trabajando encarecidamente para enfrentar esta emergencia, por lo tanto no tienen fundamentos las medidas gen\u00e9ricas de restricci\u00f3n hacia las personas procedentes de Italia, ni eventuales disuasiones a realizar viajes en todo el pa\u00eds.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ambcaracas.esteri.it\/ambasciata_caracas\/resource\/img\/2020\/02\/farnesinacorretta_info_new_en.jpg\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"1. La respuesta que Italia est\u00e1 dando a la emergencia COVID-19 (\u201cCoronavirus\u201d) ha sido tempestiva &#8211; como fue reconocido por la OMS y la UE &#8211; y marcada por la m\u00e1xima transparencia y claridad hacia la comunidad nacional y hacia los interlocutores internacionales. La preocupante proliferaci\u00f3n de noticias inexactas y alarmantes sobre la situaci\u00f3n sanitaria [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-811","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/comments?post=811"}],"version-history":[{"count":0,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/811\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/media?parent=811"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/tags?post=811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}