{"id":766,"date":"2020-10-05T17:52:15","date_gmt":"2020-10-05T15:52:15","guid":{"rendered":"https:\/\/conscaracas.esteri.it\/news\/dal_consolato\/2020\/10\/aggiornamento-del-portale-della-2\/"},"modified":"2020-10-05T17:52:15","modified_gmt":"2020-10-05T15:52:15","slug":"aggiornamento-del-portale-della-2","status":"publish","type":"post","link":"https:\/\/conscaracas.esteri.it\/es\/news\/dal_consolato\/2020\/10\/aggiornamento-del-portale-della-2\/","title":{"rendered":"Actualizaci\u00f3n del portal para la ciudadan\u00eda por matrimonio"},"content":{"rendered":"<p>El Ministerio de Interiores ha se\u00f1alado que a partir del pr\u00f3ximo mes de noviembre pondr\u00e1 a\u00a0disposici\u00f3n el nuevo portal CIVES para la gesti\u00f3n inform\u00e1tica de las solicitudes de la concesi\u00f3n de la ciudadan\u00eda por matrimonio, en sostituci\u00f3n del actual portal ALI.<\/p>\n<p>Se invitan, por lo tanto, a los solicitantes de la ciudadan\u00eda por matrimonio a visitar el nuevo portal, en cuanto est\u00e9 disponible el respectivo link en nuestra p\u00e1gina web.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"El Ministerio de Interiores ha se\u00f1alado que a partir del pr\u00f3ximo mes de noviembre pondr\u00e1 a\u00a0disposici\u00f3n el nuevo portal CIVES para la gesti\u00f3n inform\u00e1tica de las solicitudes de la concesi\u00f3n de la ciudadan\u00eda por matrimonio, en sostituci\u00f3n del actual portal ALI. Se invitan, por lo tanto, a los solicitantes de la ciudadan\u00eda por matrimonio a [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-766","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/comments?post=766"}],"version-history":[{"count":0,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/posts\/766\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/media?parent=766"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscaracas.esteri.it\/es\/wp-json\/wp\/v2\/tags?post=766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}